{"id":509,"date":"2017-07-15T13:08:44","date_gmt":"2017-07-15T18:08:44","guid":{"rendered":"http:\/\/transportercartagena.com\/?p=509\/"},"modified":"2017-07-15T13:13:53","modified_gmt":"2017-07-15T18:13:53","slug":"la-cartagena-de-garcia-marquez","status":"publish","type":"post","link":"https:\/\/transportercartagena.com\/es\/la-cartagena-de-garcia-marquez\/","title":{"rendered":"LA CARTAGENA DE GARC\u00cdA M\u00c1RQUEZ"},"content":{"rendered":"<p>\u201cS\u00f3lo basta dar un paso dentro de la muralla para ver a Cartagena de Indias en toda su grandeza. Quien la ve por primera vez, no podr\u00e1 reprimir el sentimiento de haber vuelto a nacer (Gabriel Garc\u00eda M\u00e1rquez)\u201d<br \/>\n\u00danete caminando por el Centro Hist\u00f3rico de Cartagena de Indias, en la emocionante  ruta literaria y tur\u00edstica, basado en el realismo m\u00e1gico del Nobel de Literatura, y las obras de este genial escritor. Recorreremos  La Cartagena de Garc\u00eda M\u00e1rquez de Historias reales e imaginarias, es el nombre de este paseo literario recorreremos escondites jardines, casas, y que vivieron los amores contrariados de Florentino Ariza y Fermina Daza en &#8216;El amor en los tiempos del c\u00f3lera&#8217;.   Visitaremos  el convento donde ingres\u00f3 la ni\u00f1a Sierva Mar\u00eda en (&#8216;Del amor y otros demonios&#8217;), la casa de su padre el marqu\u00e9s de Casalduero, adem\u00e1s de otros lugares vinculados con la historia personal de Garc\u00eda M\u00e1rquez. El Nobel de Literatura, recrearemos una emocionante vivencia de los espacios urbanos y la historia de esta m\u00e1gica ciudad, re interpretados en una mezcla de realidad y ficci\u00f3n a trav\u00e9s de la pluma de este nuestro gran escritor. En 35 estaciones distribuidas en 12 Plazas y 23 historias en las calles del centro amurallado. Cada estaci\u00f3n tiene historias independientes, por lo cual la selecci\u00f3n de calles y plazas  partiendo de cualquier lugar del centro hist\u00f3rico o desde el hotel donde se encuentren alojados.<\/p>\n<p><span class=\"celda\">Incluye: <\/span>Guianza<\/p>\n<p><span class=\"celda\">Duraci\u00f3n:<\/span>3 horas aproximadamente<\/p>\n<p><span class=\"celda\">Sitios de inter\u00e9s :<\/span>Casa del Marqu\u00e9s de Valdehoyos Convento de Santa Clara, ahora hotel de lujo Plaza Sim\u00f3n Bol\u00edvar El portal de los Dulces(bien pudo ser el modelo del colegio de la Presentaci\u00f3n de la Sant\u00edsima Virgen, al que acud\u00eda la protagonista antes de ser expulsada por guardar una carta de amor.) Barrio de Getseman\u00ed<br \/>\nUn lugar por el que transcurren en repetidas ocasiones los personajes de Amor en los tiempos del c\u00f3lera es el Portal de los Dulces, Paseo del Camell\u00f3n de los m\u00e1rtires<\/p>\n<p><span class=\"celda\">Recomendaciones:<\/span>Realizar el recorrido con zapatos c\u00f3modos, ropa ligera y llevar gorra o sombrero<br \/>\n<br \/>\n<div class=\"wpb_wrapper td_block_empty_space td_block_wrap vc_empty_space td_uid_1_6a56dcfaa268f_rand \"  style=\"height: 32px\"><\/div>[vc_btn title=\u00bbReservar Ahora!\u00bb style=\u00bbflat\u00bb color=\u00bbblue\u00bb i_icon_fontawesome=\u00bbfa fa-check\u00bb align=\u00bbcenter\u00bb css_animation=\u00bbbounceIn\u00bb add_icon=\u00bbtrue\u00bb link=\u00bburl:http%3A%2F%2Ftransportercartagena.com%2Fcontact%2F|||\u00bb][vc_text_separator title=\u00bbFotos\u00bb i_icon_fontawesome=\u00bbfa fa-picture-o\u00bb border_width=\u00bb2&#8243; add_icon=\u00bbtrue\u00bb]<br \/>\n<div id=\"6a56dcfaa2742\" rel=\"427\" data-gg-autoplay=\"auto\" class=\"gg_galleria_slider_wrap gg_galleria_slider_light gg_galleria_slider_show_thumbs   ggs_427\" style=\"width: 100%; height: 500px;\" ><a href=\"https:\/\/transportercartagena.com\/wp-content\/uploads\/2017\/07\/gabriel2.jpg\"><img src=\"\/\/transportercartagena.com\/wp-content\/uploads\/ewpt_cache\/60x40_100_1_c_FFFFFF_0b0c144d380c221478e54921f48a2895_gabriel2.jpg\" data-big=\"https:\/\/transportercartagena.com\/wp-content\/uploads\/2017\/07\/gabriel2.jpg\" data-description=\"\" alt=\"gabriel2\" \/><\/a><a href=\"https:\/\/transportercartagena.com\/wp-content\/uploads\/2017\/07\/gabriel3.jpg\"><img src=\"\/\/transportercartagena.com\/wp-content\/uploads\/ewpt_cache\/60x40_100_1_c_FFFFFF_4068bc44d49bf030857803d2a85908bd_gabriel3.jpg\" data-big=\"https:\/\/transportercartagena.com\/wp-content\/uploads\/2017\/07\/gabriel3.jpg\" data-description=\"\" alt=\"gabriel3\" \/><\/a><a href=\"https:\/\/transportercartagena.com\/wp-content\/uploads\/2017\/07\/gabriel4.jpg\"><img src=\"\/\/transportercartagena.com\/wp-content\/uploads\/ewpt_cache\/60x40_100_1_c_FFFFFF_88c62c3eb82018e88fbed7c234c21f68_gabriel4.jpg\" data-big=\"https:\/\/transportercartagena.com\/wp-content\/uploads\/2017\/07\/gabriel4.jpg\" data-description=\"\" alt=\"gabriel4\" \/><\/a><a href=\"https:\/\/transportercartagena.com\/wp-content\/uploads\/2017\/07\/gabriel.jpg\"><img src=\"\/\/transportercartagena.com\/wp-content\/uploads\/ewpt_cache\/60x40_100_1_c_FFFFFF_709e9a5d6cee0d7c454e3404abbf5875_gabriel.jpg\" data-big=\"https:\/\/transportercartagena.com\/wp-content\/uploads\/2017\/07\/gabriel.jpg\" data-description=\"\" alt=\"gabriel\" \/><\/a><div style=\"clear: both;\"><\/div><\/div><script type=\"text\/javascript\"> jQuery(document).ready(function($) { if(typeof(gg_galleria_init) == \"function\") { gg_galleria_show(\"#6a56dcfaa2742\");gg_galleria_init(\"#6a56dcfaa2742\");}});<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cS\u00f3lo basta dar un paso dentro de la muralla para ver a Cartagena de Indias en toda su grandeza. Quien la ve por primera vez, no podr\u00e1 reprimir el sentimiento de haber vuelto a nacer (Gabriel Garc\u00eda M\u00e1rquez)\u201d \u00danete caminando por el Centro Hist\u00f3rico de Cartagena de Indias, en la emocionante ruta literaria y tur\u00edstica, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":428,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[49],"tags":[],"yst_prominent_words":[],"_links":{"self":[{"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/posts\/509"}],"collection":[{"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/comments?post=509"}],"version-history":[{"count":2,"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/posts\/509\/revisions"}],"predecessor-version":[{"id":511,"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/posts\/509\/revisions\/511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/media\/428"}],"wp:attachment":[{"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/media?parent=509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/categories?post=509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/tags?post=509"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/transportercartagena.com\/es\/wp-json\/wp\/v2\/yst_prominent_words?post=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}